
{"id":3102,"date":"2026-01-27T16:10:21","date_gmt":"2026-01-27T08:10:21","guid":{"rendered":"https:\/\/www.ztnzenmind.com\/?post_type=courses&#038;p=3102"},"modified":"2026-01-27T16:10:22","modified_gmt":"2026-01-27T08:10:22","slug":"%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5","status":"publish","type":"courses","link":"https:\/\/ztnzenmindful.com\/zh\/courses\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\/","title":{"rendered":"\u8d70\u5411\u6bcd\u4eb2\uff5c\u6e05\u7406\u7597\u6108\u8425 | \u4e8c\u8425"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":3202,"template":"","course-category":[64],"course-tag":[],"class_list":["post-3102","courses","type-courses","status-publish","has-post-thumbnail","hentry","course-category-micro-course"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u8d70\u5411\u6bcd\u4eb2\uff5c\u6e05\u7406\u7597\u6108\u8425 | \u4e8c\u8425 - \u6771\u65b9\u5fc3\u6d41\u51a5\u60f3\u8ab2\u7a0b<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/\u8d70\u5411\u6bcd\u4eb2\u6e05\u7406\u7597\u6108\u8425-\u4e8c\u8425\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u8d70\u5411\u6bcd\u4eb2\uff5c\u6e05\u7406\u7597\u6108\u8425 | \u4e8c\u8425\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/\u8d70\u5411\u6bcd\u4eb2\u6e05\u7406\u7597\u6108\u8425-\u4e8c\u8425\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6771\u65b9\u5fc3\u6d41\u51a5\u60f3\u8ab2\u7a0b\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T08:10:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ztnzenmindful.com\/wp-content\/uploads\/2025\/06\/\u5206\u4eab\u56fe\u7247.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/courses\\\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\\\/\",\"url\":\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/courses\\\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\\\/\",\"name\":\"\u8d70\u5411\u6bcd\u4eb2\uff5c\u6e05\u7406\u7597\u6108\u8425 | \u4e8c\u8425 - \u6771\u65b9\u5fc3\u6d41\u51a5\u60f3\u8ab2\u7a0b\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jobs.ztnzenmind.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/courses\\\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/courses\\\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ztnzenmindful.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/\u5206\u4eab\u56fe\u7247.jpeg\",\"datePublished\":\"2026-01-27T08:10:21+00:00\",\"dateModified\":\"2026-01-27T08:10:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/courses\\\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\\\/#breadcrumb\"},\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/courses\\\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/courses\\\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ztnzenmindful.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/\u5206\u4eab\u56fe\u7247.jpeg\",\"contentUrl\":\"https:\\\/\\\/ztnzenmindful.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/\u5206\u4eab\u56fe\u7247.jpeg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/courses\\\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\\\/\\\/ztnzenmind.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u8ab2\u7a0b\",\"item\":\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u51a5\u60f3\u5c0f\u8bfe\",\"item\":\"https:\\\/\\\/www.ztnzenmindful.com\\\/zh_tw\\\/course-category\\\/micro-course\\\/?tutor-course-filter-category=64\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u8d70\u5411\u6bcd\u4eb2\uff5c\u6e05\u7406\u7597\u6108\u8425 | \u4e8c\u8425\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jobs.ztnzenmind.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/jobs.ztnzenmind.com\\\/en\\\/\",\"name\":\"\u58a8\u5c14\u51a5\u60f3-\u4e1c\u65b9\u5fc3\u6d41\u51a5\u60f3\",\"description\":\"\u8a79\u5510\u5be7-\u6771\u65b9\u51a5\u60f3\",\"publisher\":{\"@id\":\"https:\\\/\\\/jobs.ztnzenmind.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jobs.ztnzenmind.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jobs.ztnzenmind.com\\\/en\\\/#organization\",\"name\":\"\u58a8\u5c14\u51a5\u60f3\",\"url\":\"https:\\\/\\\/jobs.ztnzenmind.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\\\/\\\/jobs.ztnzenmind.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ztnzenmindful.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/tos-cn-i-0813c001_oQtz7WeBArzI0Boh2wfF2EAuA6AjIgCFOKANwAc5_300x300.jpeg\",\"contentUrl\":\"https:\\\/\\\/ztnzenmindful.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/tos-cn-i-0813c001_oQtz7WeBArzI0Boh2wfF2EAuA6AjIgCFOKANwAc5_300x300.jpeg\",\"width\":300,\"height\":300,\"caption\":\"\u58a8\u5c14\u51a5\u60f3\"},\"image\":{\"@id\":\"https:\\\/\\\/jobs.ztnzenmind.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/@ZHANTANGNING-EasternMeditation\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u8d70\u5411\u6bcd\u4eb2\uff5c\u6e05\u7406\u7597\u6108\u8425 | \u4e8c\u8425 - \u6771\u65b9\u5fc3\u6d41\u51a5\u60f3\u8ab2\u7a0b","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/\u8d70\u5411\u6bcd\u4eb2\u6e05\u7406\u7597\u6108\u8425-\u4e8c\u8425\/","og_locale":"zh_TW","og_type":"article","og_title":"\u8d70\u5411\u6bcd\u4eb2\uff5c\u6e05\u7406\u7597\u6108\u8425 | \u4e8c\u8425","og_url":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/\u8d70\u5411\u6bcd\u4eb2\u6e05\u7406\u7597\u6108\u8425-\u4e8c\u8425\/","og_site_name":"\u6771\u65b9\u5fc3\u6d41\u51a5\u60f3\u8ab2\u7a0b","article_modified_time":"2026-01-27T08:10:22+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.ztnzenmindful.com\/wp-content\/uploads\/2025\/06\/\u5206\u4eab\u56fe\u7247.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\/","url":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\/","name":"\u8d70\u5411\u6bcd\u4eb2\uff5c\u6e05\u7406\u7597\u6108\u8425 | \u4e8c\u8425 - \u6771\u65b9\u5fc3\u6d41\u51a5\u60f3\u8ab2\u7a0b","isPartOf":{"@id":"https:\/\/jobs.ztnzenmind.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\/#primaryimage"},"image":{"@id":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\/#primaryimage"},"thumbnailUrl":"https:\/\/ztnzenmindful.com\/wp-content\/uploads\/2025\/06\/\u5206\u4eab\u56fe\u7247.jpeg","datePublished":"2026-01-27T08:10:21+00:00","dateModified":"2026-01-27T08:10:22+00:00","breadcrumb":{"@id":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\/#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\/"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\/#primaryimage","url":"https:\/\/ztnzenmindful.com\/wp-content\/uploads\/2025\/06\/\u5206\u4eab\u56fe\u7247.jpeg","contentUrl":"https:\/\/ztnzenmindful.com\/wp-content\/uploads\/2025\/06\/\u5206\u4eab\u56fe\u7247.jpeg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/%e8%b5%b0%e5%90%91%e6%af%8d%e4%ba%b2%e6%b8%85%e7%90%86%e7%96%97%e6%84%88%e8%90%a5-%e4%ba%8c%e8%90%a5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/ztnzenmind.com\/"},{"@type":"ListItem","position":2,"name":"\u8ab2\u7a0b","item":"https:\/\/www.ztnzenmindful.com\/zh_tw\/courses\/"},{"@type":"ListItem","position":3,"name":"\u51a5\u60f3\u5c0f\u8bfe","item":"https:\/\/www.ztnzenmindful.com\/zh_tw\/course-category\/micro-course\/?tutor-course-filter-category=64"},{"@type":"ListItem","position":4,"name":"\u8d70\u5411\u6bcd\u4eb2\uff5c\u6e05\u7406\u7597\u6108\u8425 | \u4e8c\u8425"}]},{"@type":"WebSite","@id":"https:\/\/jobs.ztnzenmind.com\/en\/#website","url":"https:\/\/jobs.ztnzenmind.com\/en\/","name":"\u58a8\u5c14\u51a5\u60f3-\u4e1c\u65b9\u5fc3\u6d41\u51a5\u60f3","description":"\u8a79\u5510\u5be7-\u6771\u65b9\u51a5\u60f3","publisher":{"@id":"https:\/\/jobs.ztnzenmind.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jobs.ztnzenmind.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"},{"@type":"Organization","@id":"https:\/\/jobs.ztnzenmind.com\/en\/#organization","name":"\u58a8\u5c14\u51a5\u60f3","url":"https:\/\/jobs.ztnzenmind.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/jobs.ztnzenmind.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ztnzenmindful.com\/wp-content\/uploads\/2025\/07\/tos-cn-i-0813c001_oQtz7WeBArzI0Boh2wfF2EAuA6AjIgCFOKANwAc5_300x300.jpeg","contentUrl":"https:\/\/ztnzenmindful.com\/wp-content\/uploads\/2025\/07\/tos-cn-i-0813c001_oQtz7WeBArzI0Boh2wfF2EAuA6AjIgCFOKANwAc5_300x300.jpeg","width":300,"height":300,"caption":"\u58a8\u5c14\u51a5\u60f3"},"image":{"@id":"https:\/\/jobs.ztnzenmind.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/@ZHANTANGNING-EasternMeditation"]}]}},"_links":{"self":[{"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/courses\/3102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/types\/courses"}],"author":[{"embeddable":true,"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":4,"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/courses\/3102\/revisions"}],"predecessor-version":[{"id":33640,"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/courses\/3102\/revisions\/33640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/media\/3202"}],"wp:attachment":[{"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/media?parent=3102"}],"wp:term":[{"taxonomy":"course-category","embeddable":true,"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/course-category?post=3102"},{"taxonomy":"course-tag","embeddable":true,"href":"https:\/\/ztnzenmindful.com\/zh\/wp-json\/wp\/v2\/course-tag?post=3102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}